{"id":3,"count":158,"description":"","link":"https:\/\/www.kikidesignsla.com\/index.php\/category\/bedroom\/","name":"Bedroom","slug":"bedroom","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.kikidesignsla.com\/index.php\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kikidesignsla.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.kikidesignsla.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.kikidesignsla.com\/index.php\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}